{"id":101358,"date":"2021-11-18T00:40:55","date_gmt":"2021-11-17T23:40:55","guid":{"rendered":"https:\/\/hankook.win\/gewinnspiele\/hyundai-winter-experience-2022\/"},"modified":"2022-03-03T20:41:40","modified_gmt":"2022-03-03T19:41:40","slug":"hyundai-winter-experience-2022","status":"publish","type":"page","link":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/","title":{"rendered":"Winter Experience S\u00f6lden 2022"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; full_height=&#8220;yes&#8220; columns_placement=&#8220;bottom&#8220; awb_type=&#8220;video&#8220; awb_image_background_position=&#8220;0% 90%&#8220; awb_video_mobile=&#8220;1&#8243; awb_color=&#8220;rgba(0,0,0,0.1)&#8220; awb_image=&#8220;100836&#8243; el_class=&#8220;hde-intro-visual&#8220; awb_video_mp4=&#8220;https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/2021-09-29_HDX_Winterexperience_Landingpage_Header_Loop_Desktop_v03_Sound-web-F1-lowres.mp4&#8243;][vc_column][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_empty_space height=&#8220;340px&#8220; el_class=&#8220;intro-hde-spacer&#8220;][vc_column_text]<\/p>\n<h2 class=\"color-white\">Gewinne die atemberaubende <span class=\"nobreak\">Winter Experience<\/span><\/h2>\n<h4 class=\"color-white\">inklusive Hin- und R\u00fcckreise sowie \u00dcbernachtung <span class=\"nobreak\">im 5-Sterne-Wellnessresort<\/span><\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Jetzt durchstarten&#8220; style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;warning&#8220; align=&#8220;left&#8220; link=&#8220;url:%23intro-description|title:Jetzt%20durchstarten&#8220; el_class=&#8220;hankook-button ps2id&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;27257&#8243; img_size=&#8220;full&#8220; alignment=&#8220;right&#8220; el_class=&#8220;hde-compositlogo&#8220;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#000000&#8243; el_class=&#8220;consumption-information-section&#8220;][vc_column][vc_tta_accordion style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;black&#8220; c_icon=&#8220;chevron&#8220; c_position=&#8220;right&#8220; active_section=&#8220;&#8220; collapsible_all=&#8220;true&#8220; el_class=&#8220;consumption-information hwd-2022&#8243;][vc_tta_section title=&#8220;Verbrauchsangaben&#8220; tab_id=&#8220;consumption-information&#8220;][vc_column_text el_class=&#8220;covid-measures-text&#8220;]<\/p>\n<p class=\"color-white legalnote-2022\">1) Kraftstoffverbrauch f\u00fcr den Hyundai TUCSON 1.6 T-GDI Plug-in-Hybrid, 195 kW (265 PS): kombiniert\/gewichtet: 1,4 l\/100 km; Stromverbrauch kombiniert\/gewichtet: 17,7 kWh\/100 km; elektrische Reichweite bei voller Batterie: 62 km; CO2-Emission kombiniert: 31 g\/km; CO2-Effizienzklasse: A+. Die angegebenen Verbrauchs und CO2-Emissionswerte wurden nach dem vorgeschriebenen WLTP-Messverfahren ermittelt.<\/p>\n<p class=\"color-white legalnote-2022\">2) Kraftstoffverbrauch f\u00fcr den Hyundai SANTA FE 1.6 T-GDI Plug-in-Hybrid, 195 kW (265 PS): kombiniert\/gewichtet: 1,5 l\/100 km; Stromverbrauch kombiniert\/gewichtet: 16,3 kWh\/100 km; elektrische Reichweite bei voller Batterie: 70 km; CO2-Emission kombiniert: 34 g\/km; CO2-Effizienzklasse: A+. Die angegebenen Verbrauchs- und CO2-Emissionswerte wurden nach dem vorgeschriebenen WLTP-Messverfahren ermittelt und in NEFZ-Werte umgerechnet.<\/p>\n<p class=\"color-white legalnote-2022\">3) Stromverbrauch f\u00fcr den Hyundai IONIQ 5, 225 kW (305 PS) Allradantrieb Elektro, 72,6 kWh Batterie, Reduktionsgetriebe, 19-Zoll-Leichtmetallfelgen: kombiniert: 17,7 kWh\/100 km; elektrische Reichweite bei voller Batterie: 460 km; CO2-Emission kombiniert: 0 g\/km; CO2-Effizienzklasse: A+. Die angegebenen Verbrauchs- und CO2-Emissionswerte wurden nach dem vorgeschriebenen WLTP-Messverfahren ermittelt.<\/p>\n<p class=\"color-white legalnote-2022\">4) Kraftstoffverbrauch f\u00fcr den Hyundai i20 N 1.6 T-GDI 150 kW (204 PS) Frontantrieb Benzin, 6-Gang-Getriebe: kombiniert: 7,0 l\/100 km; CO2-Emission kombiniert: 158 g\/km; CO2-Effizienzklasse: F. Die angegebenen Verbrauchs und CO2-Emissionswerte wurden nach dem vorgeschriebenen WLTP-Messverfahren ermittelt.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row el_id=&#8220;intro-description&#8220;][vc_column][vc_empty_space height=&#8220;120px&#8220; el_class=&#8220;hwe-spacer-120-intro-descrption&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner offset=&#8220;vc_col-lg-8 vc_col-md-12 vc_col-xs-12&#8243;][vc_column_text el_class=&#8220;hde-text-block-description&#8220;]<\/p>\n<h3>Winter Experience S\u00f6lden<\/h3>\n<h4 class=\"color-orange\">Bezwinge Schnee und Eis auf Europas h\u00f6chsten Stra\u00dfen am Steuer <span class=\"nobreak\">von drei Hyundai Modellen<\/span><\/h4>\n<p>[\/vc_column_text][vc_column_text el_class=&#8220;hde-text-block-description&#8220;]Hankook l\u00e4dt dich dazu ein, Europas h\u00f6chste und eisigste Stra\u00dfen auf zwei exklusiv reservierten Gletschern in S\u00f6lden, Tirol, zu erleben. 2800 Meter \u00fcber dem Meeresspiegel bringst du drei Hyundai Modelle (Tucson, Santa Fe und IONIQ5) bei extremen Winterkonditionen auf Hochtouren. Jedes Fahrzeug ist mit Hankook Performance-Winterreifen ausgestattet, die dir selbst bei den wildesten Fahrman\u00f6vern zuverl\u00e4ssig Grip verleihen.<\/p>\n<p>Am Abend deines 2,5-t\u00e4gigen Aufenthaltes k\u00f6nnen du und ein Mitreisender dieses einmalige Erlebnis im Spa-Bereich eures 5-Sterne-Wellness-Resorts \u201eDas Central\u201c Revue passieren lassen. Die Hotelunterkunft und die Hin- und R\u00fcckreise aus einem beliebigen europ\u00e4ischen Land sind in diesem exklusiven Preispaket enthalten.[\/vc_column_text][vc_btn title=&#8220;Deine Ausr\u00fcstung&#8220; style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;warning&#8220; align=&#8220;left&#8220; link=&#8220;url:%23equipment|title:Deine%20Ausr%C3%BCstung&#8220; el_class=&#8220;hankook-button ps2id&#8220;][\/vc_column_inner][vc_column_inner el_class=&#8220;hde-boxed-element lightgrey&#8220; offset=&#8220;vc_col-lg-4 vc_col-md-12 vc_col-xs-12 vc_hidden-xs&#8220;][vc_column_text el_class=&#8220;covid-19-textblock&#8220;]<\/p>\n<h5 style=\"padding-bottom: 20px;\">COVID-19 Ma\u00dfnahmen bei der <span class=\"nobreak\">Hyundai Driving Experience<\/span><\/h5>\n<p>Um eine weitere Ausbreitung von COVID-19 zu verhindern und f\u00fcr die Sicherheit aller Teilnehmer und Mitarbeiter zu sorgen, haben wir f\u00fcr die Trainings und das Rahmenprogramm der <span class=\"nobreak\">Hyundai Driving Experience<\/span> umfangreiche Vorkehrungen getroffen. Neben strengen Hygienema\u00dfnahmen hinsichtlich der Trainingsfahrzeuge, der Hospitality und den Hotelaufenthalten z\u00e4hlen dazu auch Vorgaben zur Einhaltung des Sicherheitsabstandes zwischen allen Beteiligten.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;180px&#8220; el_class=&#8220;hwe-spacer-180-intro-descrption&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#f1f1f1&#8243; el_class=&#8220;covid-19-measures-section hdw-2022&#8243;][vc_column offset=&#8220;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8220;][vc_tta_accordion style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;white&#8220; c_icon=&#8220;chevron&#8220; c_position=&#8220;right&#8220; active_section=&#8220;&#8220; collapsible_all=&#8220;true&#8220; el_class=&#8220;covid-19-measures hwd-2022&#8243;][vc_tta_section title=&#8220;Covid-19 Ma\u00dfnahmen&#8220; tab_id=&#8220;covid-19-measures&#8220;][vc_column_text el_class=&#8220;covid-measures-text&#8220;]<\/p>\n<p class=\"color-black legalnote-2022\">Um eine weitere Ausbreitung von COVID-19 zu verhindern und f\u00fcr die Sicherheit aller Teilnehmer und Mitarbeiter zu sorgen, haben wir f\u00fcr die Trainings und das Rahmenprogramm der <span class=\"nobreak\">Hyundai Driving Experience<\/span> umfangreiche Vorkehrungen getroffen. Neben strengen Hygienema\u00dfnahmen hinsichtlich der Trainingsfahrzeuge, der Hospitality und den Hotelaufenthalten z\u00e4hlen dazu auch Vorgaben zur Einhaltung des Sicherheitsabstandes zwischen allen Beteiligten.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; awb_type=&#8220;image&#8220; awb_image_background_position=&#8220;50% 85%&#8220; awb_color=&#8220;rgba(0,0,0,0.01)&#8220; awb_image=&#8220;100856&#8243; el_class=&#8220;hwe-section-visual&#8220;][vc_column][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_empty_space height=&#8220;400px&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; content_placement=&#8220;middle&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#f7f7f7&#8243; el_id=&#8220;equipment&#8220;][vc_column][vc_empty_space height=&#8220;120px&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Deine Ausr\u00fcstung<\/h2>\n<h3 class=\"color-orange\" style=\"text-align: center;\">3 Hyundai Modelle und High Performance Winterreifen<\/h3>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;10px&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280 gallery-equipment&#8220;][vc_column_inner][vc_raw_html]JTVCcmxfZ2FsbGVyeSUyMGlkJTNEJTIyMTAyMjMwJTIyJTVE[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;100px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; content_placement=&#8220;middle&#8220; awb_type=&#8220;image&#8220; awb_image_background_position=&#8220;54% 8%&#8220; awb_color=&#8220;rgba(0,9,18,0.7)&#8220; awb_image=&#8220;101031&#8243; el_class=&#8220;hwe-section-visual&#8220; el_id=&#8220;preparation&#8220;][vc_column][vc_empty_space height=&#8220;100px&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_column_text el_class=&#8220;hde-text-block-description&#8220;]<\/p>\n<h3 class=\"color-white\" style=\"text-align: center;\">Deine Vorbereitung<\/h3>\n<h4 class=\"color-white\" style=\"text-align: center;\">Um f\u00fcr deine <span class=\"nobreak\">Winter Experience<\/span> optimal vorbereitet zu sein, <span class=\"nobreak\">bringe bitte Folgendes mit:<\/span><\/h4>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;30px&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-3 vc_col-md-6 vc_col-xs-12&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3280\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:140px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-preparation-icon-01-F2.svg\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3280 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;mobile_landscape:15px;\",\"line-height\":\"\"}'  style=\"color:#f47d31;\">2G<sup>+<\/sup> Nachweis<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3280 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"desktop:14px;mobile_landscape:13px;\",\"line-height\":\"\"}'  style=\"color:#ffffff;\">durch den (digitalen) Impfausweis ODER COVID-Nachweis der Genesung<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-3 vc_col-md-6 vc_col-xs-12&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5985\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:140px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-preparation-icon-02-F1.svg\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5985 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;mobile_landscape:15px;\",\"line-height\":\"\"}'  style=\"color:#f47d31;\">Negativer Covid-19-Test<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5985 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"desktop:14px;mobile_landscape:13px;\",\"line-height\":\"\"}'  style=\"color:#ffffff;\">Schnelltest, nicht \u00e4lter als 24 Stunden. Wir ben\u00f6tigen einen negativen Test, auch dann wenn du bereits geboostert bist.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-3 vc_col-md-6 vc_col-xs-12&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-9433\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:140px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-preparation-icon-03-F1.svg\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9433 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;mobile_landscape:15px;\",\"line-height\":\"\"}'  style=\"color:#f47d31;\">Unterlagen<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-9433 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"desktop:14px;mobile_landscape:13px;\",\"line-height\":\"\"}'  style=\"color:#ffffff;\">F\u00fchrerschein und Personalausweis<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-3 vc_col-md-6 vc_col-xs-12&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5944\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:140px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-preparation-icon-04-F1.svg\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5944 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;mobile_landscape:15px;\",\"line-height\":\"\"}'  style=\"color:#f47d31;\">Bekleidung<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5944 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"desktop:14px;mobile_landscape:13px;\",\"line-height\":\"\"}'  style=\"color:#ffffff;\">Bequeme, wintertaugliche Kleidung und Schuhe<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;100px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; awb_type=&#8220;image&#8220; awb_stretch=&#8220;1&#8243; awb_image_background_position=&#8220;45% 50%&#8220; el_id=&#8220;prize&#8220; awb_image=&#8220;100961&#8243;][vc_column][vc_empty_space height=&#8220;120px&#8220; el_class=&#8220;hwe-spacer-120-prizes&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243; css=&#8220;.vc_custom_1637070021727{padding-right: 15px !important;padding-left: 15px !important;}&#8220;][vc_column_inner][vc_column_text]<\/p>\n<h2 class=\"color-white\" style=\"text-align: center;\">Die Preise<\/h2>\n<h3 class=\"color-white\" style=\"text-align: center; max-width: 900px; margin: 0 auto;\">Gewinne ein einmaliges Fahrerlebnis in den Alpen oder einen Satz Hankook <span class=\"nobreak\">Performance Winterreifen<\/span><\/h3>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220; el_class=&#8220;hwe-spacer-80-prizes&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_column_text el_class=&#8220;hk-splash-width-headline-black&#8220;]<\/p>\n<h3 class=\"color-white\">1. Preis<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h3 class=\"color-orange\" style=\"margin-bottom: 0px;\">Winter Experience S\u00f6lden<\/h3>\n<h5 class=\"color-black\" style=\"margin-bottom: 0px;\">21.03. &#8211; 23.03.2022<\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 class=\"color-black\" style=\"margin-bottom: 0px;\">\u2022 exklusive Reise f\u00fcr 2 Personen <span class=\"nobreak\">(2,5 Tage)<\/span><br \/>\n\u2022 Teilnahme an der <span class=\"nobreak\">Hyundai Driving Experience<\/span><br \/>\n\u2022 Hin- und R\u00fcckflug aus einem beliebigen europ\u00e4ischen Land<br \/>\n\u2022 5-Sterne-Wellness-Resort-Aufenthalt <span class=\"nobreak\">(\u201eDas Central\u201c)<\/span><\/h5>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;500px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; awb_type=&#8220;image&#8220; awb_image_background_position=&#8220;50% 100%&#8220; awb_image=&#8220;101006&#8243;][vc_column][vc_empty_space height=&#8220;160px&#8220; el_class=&#8220;hwe-spacer-160-prizes&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner offset=&#8220;vc_col-lg-2\/5 vc_col-md-2\/5 vc_col-xs-12&#8243;][vc_column_text el_class=&#8220;hk-splash-width-headline-white&#8220;]<\/p>\n<h3 class=\"color-black\">2. Preis<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h3 class=\"color-orange\" style=\"margin-bottom: 0px;\">4x S\u00e4tze Hankook Reifen<\/h3>\n<h5 class=\"color-white\" style=\"margin-bottom: 0px;\">High Performance Winterreifen<\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 class=\"color-white\" style=\"margin-bottom: 0px;\">\u2022 Gewinner w\u00e4hlen zwischen <span class=\"nobreak\">Winter i*cept evo3<\/span> und <span class=\"nobreak\">Winter i*cept evo3 X<\/span> <span class=\"nobreak\">(Spezial-Reifen f\u00fcr SUVs)<\/span><\/h5>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;50px&#8220;][vc_single_image image=&#8220;101433&#8243; img_size=&#8220;full&#8220; el_class=&#8220;hwd-2022-tyre-set&#8220;][vc_empty_space height=&#8220;60px&#8220;][\/vc_column_inner][vc_column_inner offset=&#8220;vc_col-lg-1\/5 vc_col-md-1\/5 vc_col-xs-12&#8243;][\/vc_column_inner][vc_column_inner offset=&#8220;vc_col-lg-2\/5 vc_col-md-2\/5 vc_col-xs-12&#8243;][vc_column_text el_class=&#8220;hk-splash-width-headline-white&#8220;]<\/p>\n<h3 class=\"color-black\">3. Preis<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h3 class=\"color-orange\" style=\"margin-bottom: 0px;\">10x FLSK-Thermoflaschen<\/h3>\n<h5 class=\"color-white\" style=\"margin-bottom: 0px;\">elegantes schwarzes Design mit silbernem Deckel<\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 class=\"color-white\" style=\"margin-bottom: 0px;\">\u2022 Getr\u00e4nke bleiben bis zu 18 h hei\u00df oder bis zu 24 h kalt<br \/>\n\u2022 mit eingraviertem Hankook-Logo<\/h5>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;50px&#8220;][vc_single_image image=&#8220;101609&#8243; img_size=&#8220;full&#8220; el_class=&#8220;hwd-2022-thermo-bottles&#8220;][vc_empty_space height=&#8220;60px&#8220; el_class=&#8220;hwe-spacer-60-prizes&#8220;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;40px&#8220; el_class=&#8220;hwe-spacer-40-prizes&#8220;][\/vc_column][\/vc_row][vc_row el_id=&#8220;challenge&#8220;][vc_column][vc_empty_space height=&#8220;80px&#8220;][vc_row_inner el_class=&#8220;boxed-maxwidth-800&#8243;][vc_column_inner][vc_column_text]<\/p>\n<h2 class=\"color-black\">Das Gewinnspiel<\/h2>\n<p>[\/vc_column_text][vc_column_text el_class=&#8220;hde-boxed-element-text lightgrey challenge&#8220;]<\/p>\n<h4><span class=\"color-orange\">Hyundai Driving Experience &#8211;<\/span> <span class=\"nobreak color-orange\">Winter Experience<\/span><\/h4>\n<h5>Ankunft: 21.03.2022 | <span class=\"nobreak\">Event: 22.03.2022<\/span> | <span class=\"nobreak\">Teilnahmeschluss:<\/span> <span class=\"nobreak\">16.03.2022 \u2013 10.00<\/span><\/h5>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8220;boxed-maxwidth-800&#8243;][vc_column_inner]<div class=\"hankook-challenge-expired-message\">\r\n<h4 class=\"hankook-headline color-orange\" style=\"text-align: center;\">Teilnahme abgelaufen<\/h4>\r\n\r\n<h4 class=\"hankook-headline\" style=\"text-align: center;\">Sorry, Du bist leider etwas zu sp\u00e4t dran! Der Teilnahmeschluss f\u00fcr das ausgew\u00e4hlte Gewinnspiel ist bereits abgelaufen.<\/h4><\/div>[\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; full_height=&#8220;yes&#8220; columns_placement=&#8220;bottom&#8220; awb_type=&#8220;video&#8220; awb_image_background_position=&#8220;0% 90%&#8220; awb_video_mobile=&#8220;1&#8243; awb_color=&#8220;rgba(0,0,0,0.1)&#8220; awb_image=&#8220;100836&#8243; el_class=&#8220;hde-intro-visual&#8220; awb_video_mp4=&#8220;https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/2021-09-29_HDX_Winterexperience_Landingpage_Header_Loop_Desktop_v03_Sound-web-F1-lowres.mp4&#8243;][vc_column][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_empty_space height=&#8220;340px&#8220; el_class=&#8220;intro-hde-spacer&#8220;][vc_column_text] Gewinne die atemberaubende Winter Experience inklusive Hin- und R\u00fcckreise sowie \u00dcbernachtung im 5-Sterne-Wellnessresort [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Jetzt durchstarten&#8220; style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;warning&#8220; align=&#8220;left&#8220; link=&#8220;url:%23intro-description|title:Jetzt%20durchstarten&#8220; el_class=&#8220;hankook-button ps2id&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;27257&#8243; img_size=&#8220;full&#8220; alignment=&#8220;right&#8220; el_class=&#8220;hde-compositlogo&#8220;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#000000&#8243; el_class=&#8220;consumption-information-section&#8220;][vc_column][vc_tta_accordion style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;black&#8220; c_icon=&#8220;chevron&#8220; c_position=&#8220;right&#8220; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":100899,"parent":148,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-101358","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Winter Experience S\u00f6lden 2022 - Hankook Tire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Winter Experience S\u00f6lden 2022\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; full_height=&#8220;yes&#8220; columns_placement=&#8220;bottom&#8220; awb_type=&#8220;video&#8220; awb_image_background_position=&#8220;0% 90%&#8220; awb_video_mobile=&#8220;1&#8243; awb_color=&#8220;rgba(0,0,0,0.1)&#8220; awb_image=&#8220;100836&#8243; el_class=&#8220;hde-intro-visual&#8220; awb_video_mp4=&#8220;https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/2021-09-29_HDX_Winterexperience_Landingpage_Header_Loop_Desktop_v03_Sound-web-F1-lowres.mp4&#8243;][vc_column][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_empty_space height=&#8220;340px&#8220; el_class=&#8220;intro-hde-spacer&#8220;][vc_column_text] Gewinne die atemberaubende Winter Experience inklusive Hin- und R\u00fcckreise sowie \u00dcbernachtung im 5-Sterne-Wellnessresort [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Jetzt durchstarten&#8220; style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;warning&#8220; align=&#8220;left&#8220; link=&#8220;url:%23intro-description|title:Jetzt%20durchstarten&#8220; el_class=&#8220;hankook-button ps2id&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;27257&#8243; img_size=&#8220;full&#8220; alignment=&#8220;right&#8220; el_class=&#8220;hde-compositlogo&#8220;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#000000&#8243; el_class=&#8220;consumption-information-section&#8220;][vc_column][vc_tta_accordion style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;black&#8220; c_icon=&#8220;chevron&#8220; c_position=&#8220;right&#8220; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Hankook Tire\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T19:41:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/\",\"url\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/\",\"name\":\"Winter Experience S\u00f6lden 2022 - Hankook Tire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hankook.win\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg\",\"datePublished\":\"2021-11-17T23:40:55+00:00\",\"dateModified\":\"2022-03-03T19:41:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hankook.win\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg\",\"contentUrl\":\"https:\\\/\\\/hankook.win\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/hyundai-winter-experience-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hankook.win\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gewinnspiele\",\"item\":\"https:\\\/\\\/hankook.win\\\/de\\\/gewinnspiele\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Winter Experience S\u00f6lden 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hankook.win\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hankook.win\\\/de\\\/\",\"name\":\"Hankook Tire\",\"description\":\"Win with Hankook\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hankook.win\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Winter Experience S\u00f6lden 2022 - Hankook Tire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/","og_locale":"de_DE","og_type":"article","og_title":"Winter Experience S\u00f6lden 2022","og_description":"[vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; full_height=&#8220;yes&#8220; columns_placement=&#8220;bottom&#8220; awb_type=&#8220;video&#8220; awb_image_background_position=&#8220;0% 90%&#8220; awb_video_mobile=&#8220;1&#8243; awb_color=&#8220;rgba(0,0,0,0.1)&#8220; awb_image=&#8220;100836&#8243; el_class=&#8220;hde-intro-visual&#8220; awb_video_mp4=&#8220;https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/2021-09-29_HDX_Winterexperience_Landingpage_Header_Loop_Desktop_v03_Sound-web-F1-lowres.mp4&#8243;][vc_column][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner][vc_empty_space height=&#8220;340px&#8220; el_class=&#8220;intro-hde-spacer&#8220;][vc_column_text] Gewinne die atemberaubende Winter Experience inklusive Hin- und R\u00fcckreise sowie \u00dcbernachtung im 5-Sterne-Wellnessresort [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8220;boxed-maxwidth-1280&#8243;][vc_column_inner width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Jetzt durchstarten&#8220; style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;warning&#8220; align=&#8220;left&#8220; link=&#8220;url:%23intro-description|title:Jetzt%20durchstarten&#8220; el_class=&#8220;hankook-button ps2id&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;27257&#8243; img_size=&#8220;full&#8220; alignment=&#8220;right&#8220; el_class=&#8220;hde-compositlogo&#8220;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;80px&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row_content_no_spaces&#8220; awb_type=&#8220;color&#8220; awb_color=&#8220;#000000&#8243; el_class=&#8220;consumption-information-section&#8220;][vc_column][vc_tta_accordion style=&#8220;flat&#8220; shape=&#8220;square&#8220; color=&#8220;black&#8220; c_icon=&#8220;chevron&#8220; c_position=&#8220;right&#8220; [&hellip;]","og_url":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/","og_site_name":"Hankook Tire","article_modified_time":"2022-03-03T19:41:40+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/","url":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/","name":"Winter Experience S\u00f6lden 2022 - Hankook Tire","isPartOf":{"@id":"https:\/\/hankook.win\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/#primaryimage"},"image":{"@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg","datePublished":"2021-11-17T23:40:55+00:00","dateModified":"2022-03-03T19:41:40+00:00","breadcrumb":{"@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/#primaryimage","url":"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg","contentUrl":"https:\/\/hankook.win\/wp-content\/uploads\/2022\/03\/hankook_win-hyundai-winter-experience-2022-grid-F1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/hankook.win\/de\/gewinnspiele\/hyundai-winter-experience-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hankook.win\/de\/"},{"@type":"ListItem","position":2,"name":"Gewinnspiele","item":"https:\/\/hankook.win\/de\/gewinnspiele\/"},{"@type":"ListItem","position":3,"name":"Winter Experience S\u00f6lden 2022"}]},{"@type":"WebSite","@id":"https:\/\/hankook.win\/de\/#website","url":"https:\/\/hankook.win\/de\/","name":"Hankook Tire","description":"Win with Hankook","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hankook.win\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/pages\/101358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/comments?post=101358"}],"version-history":[{"count":0,"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/pages\/101358\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/pages\/148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/media\/100899"}],"wp:attachment":[{"href":"https:\/\/hankook.win\/de\/wp-json\/wp\/v2\/media?parent=101358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}